{"id":4154,"date":"2020-05-18T15:25:25","date_gmt":"2020-05-18T19:25:25","guid":{"rendered":"https:\/\/blacmcstaging.wpengine.com\/?post_type=project&#038;p=4154"},"modified":"2025-07-26T02:39:56","modified_gmt":"2025-07-26T06:39:56","slug":"installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf","status":"publish","type":"project","link":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","title":{"rendered":"Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf"},"content":{"rendered":"<style>\n    .get-in-touch .join-the-team p{\n        margin-bottom: 1rem;\n    }\n    .get-in-touch .join-the-team img{\n        width: 100%;\n        margin: 0 0 20px;\n    }\n    .get-in-touch .join-the-team .cta{\n        text-align: left;\n    }\n    .get-in-touch .join-the-team h1{\n        margin-bottom: 1.75rem;\n    }\n<\/style>\n\n<div id=\"work-with-us-block_5e7cea5c0149b\" class=\"get-in-touch alignfull \">\n    <div class=\"row\">\n        <div class=\"large-5 column\">\n            <div class=\"contact\">\n                <h1>Restez en contact<\/h1>\n                <div class=\"the-form\">\n\t\t    <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_15' ><div id='gf_15' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_15' id='gform_15'  action='\/fr\/wp-json\/wp\/v2\/project\/4154#gf_15' data-formid='15' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_15' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_15_14\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_14'>Company<\/label><div class='ginput_container'><input name='input_14' id='input_15_14' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_15_14'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_15_1\" class=\"gfield gfield--type-text gfield--input-type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_1'>Pr\u00e9nom<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_15_1' type='text' value='' class='large'    placeholder='Pr\u00e9nom' aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"given-name\" \/><\/div><\/li><li id=\"field_15_3\" class=\"gfield gfield--type-text gfield--input-type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_3'>Nom de famille<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_15_3' type='text' value='' class='large'    placeholder='Nom de famille' aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"family-name\" \/><\/div><\/li><li id=\"field_15_2\" class=\"gfield gfield--type-email gfield--input-type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_2'>Votre courriel<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_15_2' type='email' value='' class='large'   placeholder='Courriel' aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"email\"\/>\n                        <\/div><\/li><li id=\"field_15_8\" class=\"gfield gfield--type-text gfield--input-type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_8'>T\u00e9l\u00e9phone<\/label><div class='ginput_container ginput_container_text'><input name='input_8' id='input_15_8' type='text' value='' class='medium'    placeholder='T\u00e9l\u00e9phone'  aria-invalid=\"false\"  autocomplete=\"tel\" \/><\/div><\/li><li id=\"field_15_7\" class=\"gfield gfield--type-select gfield--input-type-select field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_7'>Emplacement B&amp;M<\/label><div class='ginput_container ginput_container_select'><select name='input_7' id='input_15_7' class='medium gfield_select'     aria-invalid=\"false\" ><option value='Entreprise' >Entreprise<\/option><option value='St. John&#039;s, NL' >St. John&#039;s, NL<\/option><option value='Goose Bay, NL' >Goose Bay, NL<\/option><option value='Bathurst, NB' >Bathurst, NB<\/option><option value='Fredericton, NB' >Fredericton, NB<\/option><option value='Moncton, NB' >Moncton, NB<\/option><option value='Saint John, NB' >Saint John, NB<\/option><option value='Dartmouth, NS' >Dartmouth, NS<\/option><option value='Montr\u00e9al, QC' >Montr\u00e9al, QC<\/option><option value='London, ON' >London, ON<\/option><option value='Hamilton, ON' >Hamilton, ON<\/option><option value='Ottawa, ON' >Ottawa, ON<\/option><option value='Markham, ON' >Markham, ON<\/option><option value='Scarborough, ON - Pullman Court' >Scarborough, ON &#8211; Pullman Court<\/option><option value='Scarborough, ON - Select Avenue' >Scarborough, ON &#8211; Select Avenue<\/option><option value='Scarborough, ON - Pre-Fab Shop' >Scarborough, ON &#8211; Pre-Fab Shop<\/option><option value='North York, ON - Railside' >North York, ON &#8211; Railside<\/option><option value='Courtice, ON' >Courtice, ON<\/option><option value='Tiverton, ON' >Tiverton, ON<\/option><option value='Winnipeg, MB' >Winnipeg, MB<\/option><option value='Saskatoon, SK' >Saskatoon, SK<\/option><option value='Regina, SK' >Regina, SK<\/option><option value='Calgary, AB' >Calgary, AB<\/option><option value='Edmonton, AB' >Edmonton, AB<\/option><option value='Kelowna, BC' >Kelowna, BC<\/option><option value='Vernon, BC' >Vernon, BC<\/option><option value='Vancouver, BC' >Vancouver, BC<\/option><option value='Kansas City, MO' >Kansas City, MO<\/option><option value='Springdale, AR' >Springdale, AR<\/option><option value='Salt Lake City, UT' >Salt Lake City, UT<\/option><option value='Austin, TX' >Austin, TX<\/option><option value='Tulsa, OK' >Tulsa, OK<\/option><option value='East Syracuse, NY' >East Syracuse, NY<\/option><option value='Portland, OR' >Portland, OR<\/option><option value='Hamilton, Bermuda' >Hamilton, Bermuda<\/option><\/select><\/div><\/li><li id=\"field_15_4\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_4'>Message<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_15_4' class='textarea large'     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_15_13\" class=\"gfield gfield--type-captcha gfield--input-type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_15_13'>reCAPTCHA<\/label><div id='input_15_13' class='ginput_container ginput_recaptcha' data-sitekey='6LcsPN4ZAAAAACZmqHXuZlbnAtZL0m3qf-QoH7mc'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='inline'><\/div><label for=\"g-recaptcha-response\" class=\"show-for-sr\">Recaptcha Response<\/label><\/li><li id=\"field_15_9\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_9' id='input_15_9' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Get in Touch_Corporate_Generic' \/><\/div><\/li><li id=\"field_15_10\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_10' id='input_15_10' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Unknown' \/><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_15' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Soumettre'  \/> <input type='hidden' name='gform_ajax' value='form_id=15&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;hash=6eeb70dc036ce661bc716ad4785a4207' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_15' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_15' id='gform_theme_15' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_15' id='gform_style_settings_15' value='' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_15' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='15' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CAD' value='B8xLiGIFIdzWqzZ76\/z8MYBEjRpa5yKJ5PSwxHym9564gQjTrtCoVHYwua8U3H+YIW2ZK4VRi0\/QjJ8zBo72OiWVHzlShtljYpPHJBOGuiWRXnM=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_15' value='WyJbXSIsIjg0MmY3MzVjOTIyNDM5ZWZjNjU1YTcxYmQyZTFhYTBjIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_15' id='gform_target_page_number_15' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_15' id='gform_source_page_number_15' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_15' id='gform_ajax_frame_15' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec AJAX'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 15, 'https:\/\/blackandmcdonald.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_15').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_15');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_15').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_15').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_15').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_15').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_15').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_15').val();gformInitSpinner( 15, 'https:\/\/blackandmcdonald.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [15, current_page]);window['gf_submitting_15'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_15').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_15').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [15]);window['gf_submitting_15'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_15').text());}else{jQuery('#gform_15').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"15\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_15\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_15\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_15\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 15, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"large-6 large-offset-1 column\">\n                        <div class=\"join-the-team\">\n                <h1>Joignez-vous \u00e0 notre \u00e9quipe<\/h1>\n                <p>Vous pensez qu\u2019il faut bien faire ce qui en vaut la peine. Que les solutions doivent \u00eatre durables. Que faire partie d\u2019une \u00e9quipe signifie qu\u2019il ne faut pas se limiter \u00e0 travailler pour soi, mais aussi pour les autres. C\u2019est comme cela que nous travaillons aussi. <\/p>\n                                                    <img decoding=\"async\" src=\"\/wp-content\/uploads\/Screenshot-2024-08-08-at-12.43.46-AM.png\" alt=\"Joignez-vous \u00e0 notre \u00e9quipe\" \/>\n                    \n                                                    <div class=\"cta\">\n                        <a href=\"https:\/\/blackandmcdonald.com\/fr\/carrieres\/\"  class=\"btn\">\n                            En savoir davantage                        <\/a>\n                    <\/div>\n                            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<style>\n    .newsletter-block .block-title h1{\n        text-align: center;\n    }\n    .gform_legacy_markup_wrapper .gform_body{\n        width: 78% !important;\n        display: inline-block;\n        vertical-align: middle;\n    }\n    .newsletter-block .the-form .gform_wrapper form .gform_body .gform_fields .gfield{\n        width: 26%;\n        display: inline-block;\n        vertical-align: middle;\n    }\n    .newsletter-block .the-form .gform_wrapper form .gform_body .gform_fields .gfield.gfield--input-type-email{\n        width: 45%;\n        display: inline-block;\n        vertical-align: middle;\n        padding-left: 1rem;\n    }\n    .newsletter-block .the-form .gform_wrapper form .gform_footer{\n        width: 20%;\n        display: inline-block;\n        vertical-align: middle;\n        margin: 29px 0 0;\n    }\n    @media screen and ( max-width: 480px )  {\n        .newsletter-block .the-form .gform_wrapper form .gform_body .gform_fields .gfield,\n        .newsletter-block .the-form .gform_wrapper form .gform_body .gform_fields .gfield.gfield--input-type-email,\n        .gform_legacy_markup_wrapper .gform_body{\n            width: 100% !important;\n            padding-left: 0;\n        }\n        .newsletter-block .the-form .gform_wrapper form .gform_footer{\n            width: 100%;\n            margin: 9px 0 0;\n        }\n    }\n<\/style>\n\n<div id=\"newsletter-block-block_be90638da7dc4e947053d48424c5213c\" class=\"newsletter-block alignfull \">\n    <div class=\"row\">\n        <div class=\"medium-12 column\">\n            <div class=\"block-title\">\n                <h1>Inscrivez-vous pour recevoir notre bulletin<\/h1>\n                <!-- <p><\/p> -->\n            <\/div>\n        <\/div>\n        <div class=\"medium-12 column\">\n            <div class=\"the-form\">\n                \n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_1' ><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/project\/4154#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_1_8\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_8'>Company<\/label><div class='ginput_container'><input name='input_8' id='input_1_8' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_8'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_1_2\" class=\"gfield gfield--type-text gfield--input-type-text gf_left_half newsletter-input gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_2'>Pr\u00e9nom<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_1_2' type='text' value='' class='large'    placeholder='Pr\u00e9nom' aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"given-name\" \/><\/div><\/li><li id=\"field_1_5\" class=\"gfield gfield--type-text gfield--input-type-text gf_right_half newsletter-input gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_5'>Nom de famille<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_1_5' type='text' value='' class='large'    placeholder='Nom de famille' aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"family-name\" \/><\/div><\/li><li id=\"field_1_1\" class=\"gfield gfield--type-email gfield--input-type-email newsletter-input gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>Courriel<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_1' id='input_1_1' type='email' value='' class='large'   placeholder='Entrez votre adresse email' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_1_6\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_6' id='input_1_6' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Newsletter Subscription - Canada Site' \/><\/div><\/li><li id=\"field_1_7\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_7' id='input_1_7' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Unknown' \/><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Soumettre'  \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;hash=4d148d774001c9d9b988d5f1b153e626' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CAD' value='a6VXpOLR+LT8NT7ejZi9MubiiME3VWk7nKfuIHRA7es88wVGf5LMe4eD3RHkigC3TQ0j+O5zKADFHtgYM2g0OnaF2d5Yh0UI8tbaBnan4kZfGRQ=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjg0MmY3MzVjOTIyNDM5ZWZjNjU1YTcxYmQyZTFhYTBjIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec AJAX'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/blackandmcdonald.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/blackandmcdonald.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Transformation de l\u2019usine de production industrielle de 23\u00a0000\u00a0m2 (250\u00a0000\u00a0pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.<\/p>\n","protected":false},"author":11,"featured_media":3053,"menu_order":146,"template":"","region":[43],"class_list":["post-4154","project","type-project","status-publish","has-post-thumbnail","hentry","region-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Profil de projet B&amp;M \u2013 Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf<\/title>\n<meta name=\"description\" content=\"Transformation de l\u2019usine de production industrielle de 23 000 m2 (250 000 pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf\" \/>\n<meta property=\"og:description\" content=\"Transformation de l\u2019usine de production industrielle de 23\u00a0000\u00a0m2 (250\u00a0000\u00a0pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/\" \/>\n<meta property=\"og:site_name\" content=\"Black &amp; McDonald\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlackandMcDonald\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-26T06:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bandmlimited\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/\",\"name\":\"Profil de projet B&M \u2013 Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/04102017a_Super_Portrait.jpg\",\"datePublished\":\"2020-05-18T19:25:25+00:00\",\"dateModified\":\"2025-07-26T06:39:56+00:00\",\"description\":\"Transformation de l\u2019usine de production industrielle de 23 000 m2 (250 000 pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/04102017a_Super_Portrait.jpg\",\"contentUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/04102017a_Super_Portrait.jpg\",\"width\":625,\"height\":417,\"caption\":\"B&M project profile - Facility Services - Kelowna and Vernon Jubilee Hospitals Expansion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/projects\\\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#website\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/\",\"name\":\"Black & McDonald\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blackandmcdonald.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#organization\",\"name\":\"Black & McDonald\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/BlackMcDonald_Logo.png\",\"contentUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/BlackMcDonald_Logo.png\",\"width\":1633,\"height\":844,\"caption\":\"Black & McDonald\"},\"image\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BlackandMcDonald\",\"https:\\\/\\\/x.com\\\/bandmlimited\",\"https:\\\/\\\/www.instagram.com\\\/blackandmcdonald\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/black-&amp;-mcdonald-limited\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/blackmcdonaldchannel\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profil de projet B&M \u2013 Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf","description":"Transformation de l\u2019usine de production industrielle de 23 000 m2 (250 000 pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","og_locale":"fr_CA","og_type":"article","og_title":"Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf","og_description":"Transformation de l\u2019usine de production industrielle de 23\u00a0000\u00a0m2 (250\u00a0000\u00a0pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.","og_url":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","og_site_name":"Black &amp; McDonald","article_publisher":"https:\/\/www.facebook.com\/BlackandMcDonald","article_modified_time":"2025-07-26T06:39:56+00:00","og_image":[{"width":625,"height":417,"url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bandmlimited","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","url":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","name":"Profil de projet B&M \u2013 Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf","isPartOf":{"@id":"https:\/\/blackandmcdonald.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/#primaryimage"},"image":{"@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/#primaryimage"},"thumbnailUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg","datePublished":"2020-05-18T19:25:25+00:00","dateModified":"2025-07-26T06:39:56+00:00","description":"Transformation de l\u2019usine de production industrielle de 23 000 m2 (250 000 pi2) de l\u2019entreprise MedReleaf en une usine de production de cannabis th\u00e9rapeutique et un laboratoire de recherche de calibre mondial incluant la modernisation de la plomberie, des syst\u00e8mes \u00e9lectriques et de CVCA, et l\u2019installation d\u2019un syst\u00e8me d\u2019irrigation et d\u2019un syst\u00e8me de r\u00e9gulation des conditions ambiantes.","breadcrumb":{"@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/#primaryimage","url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg","contentUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg","width":625,"height":417,"caption":"B&M project profile - Facility Services - Kelowna and Vernon Jubilee Hospitals Expansion"},{"@type":"BreadcrumbList","@id":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackandmcdonald.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Installations de production de cannabis th\u00e9rapeutique de l\u2019entreprise MedReleaf"}]},{"@type":"WebSite","@id":"https:\/\/blackandmcdonald.com\/#website","url":"https:\/\/blackandmcdonald.com\/","name":"Black & McDonald","description":"","publisher":{"@id":"https:\/\/blackandmcdonald.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackandmcdonald.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/blackandmcdonald.com\/#organization","name":"Black & McDonald","url":"https:\/\/blackandmcdonald.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/blackandmcdonald.com\/#\/schema\/logo\/image\/","url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/05\/BlackMcDonald_Logo.png","contentUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/05\/BlackMcDonald_Logo.png","width":1633,"height":844,"caption":"Black & McDonald"},"image":{"@id":"https:\/\/blackandmcdonald.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BlackandMcDonald","https:\/\/x.com\/bandmlimited","https:\/\/www.instagram.com\/blackandmcdonald\/","https:\/\/www.linkedin.com\/company\/black-&amp;-mcdonald-limited","https:\/\/www.youtube.com\/user\/blackmcdonaldchannel"]}]}},"image":"<img width=\"625\" height=\"417\" src=\"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"B&amp;M project profile - Facility Services - Kelowna and Vernon Jubilee Hospitals Expansion\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg 625w, https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait-300x200.jpg 300w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/>","image_src":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/04\/04102017a_Super_Portrait.jpg","permalink":"https:\/\/blackandmcdonald.com\/fr\/projects\/installations-de-production-de-cannabis-therapeutique-de-lentreprise-medreleaf\/","_links":{"self":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/project\/4154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/media\/3053"}],"wp:attachment":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/media?parent=4154"}],"wp:term":[{"taxonomy":"region","embeddable":true,"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/region?post=4154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}