{"id":21623,"date":"2026-05-08T12:33:00","date_gmt":"2026-05-08T16:33:00","guid":{"rendered":"https:\/\/blackandmcdonald.com\/?post_type=news&#038;p=21623"},"modified":"2026-05-11T12:37:00","modified_gmt":"2026-05-11T16:37:00","slug":"bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii","status":"publish","type":"news","link":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/","title":{"rendered":"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II"},"content":{"rendered":"\n<p>B&amp;M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la <strong>certification ISO\/IEC&nbsp;27001:2022<\/strong> et qu\u2019elle a <strong>pass\u00e9 avec succ\u00e8s un audit SOC&nbsp;2\u00ae Type&nbsp;II<\/strong>.<\/p>\n\n\n\n<p>La certification ISO&nbsp;27001 atteste que notre syst\u00e8me de gestion de la s\u00e9curit\u00e9 de l\u2019information est conforme aux normes internationalement reconnues. L\u2019audit SOC&nbsp;2\u00ae Type&nbsp;II, r\u00e9alis\u00e9 par un tiers ind\u00e9pendant, permet de v\u00e9rifier que les contr\u00f4les cl\u00e9s sont con\u00e7us et fonctionnent efficacement au fil du temps.<\/p>\n\n\n\n<p>Ensemble, ces r\u00e9alisations t\u00e9moignent de l\u2019approche pragmatique que nous mettons en \u0153uvre pour g\u00e9rer l\u2019information de mani\u00e8re responsable et garantir la fiabilit\u00e9 de notre exploitation. La protection de l\u2019information et le maintien de la confiance sont au c\u0153ur de notre activit\u00e9, et ces \u00e9tapes importantes illustrent notre engagement sans faille \u00e0 offrir un service constant et fiable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>B&amp;M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC&nbsp;27001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC&nbsp;2\u00ae Type&nbsp;II. La certification ISO&nbsp;27001 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":21625,"menu_order":0,"template":"","class_list":["post-21623","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II - Black &amp; McDonald<\/title>\n<meta name=\"description\" content=\"B&amp;M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC\u00a027001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC\u00a02\u00ae Type\u00a0II.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II\" \/>\n<meta property=\"og:description\" content=\"B&amp;M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC&nbsp;27001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC&nbsp;2\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Black &amp; McDonald\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlackandMcDonald\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T16:37:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/BM_ISO_Announcement_DigitalSignage_FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bandmlimited\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/\",\"name\":\"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II - Black &amp; McDonald\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/BM_ISO_Announcement_DigitalSignage_FR.jpg\",\"datePublished\":\"2026-05-08T16:33:00+00:00\",\"dateModified\":\"2026-05-11T16:37:00+00:00\",\"description\":\"B&M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\\\/IEC\u00a027001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC\u00a02\u00ae Type\u00a0II.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/BM_ISO_Announcement_DigitalSignage_FR.jpg\",\"contentUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/BM_ISO_Announcement_DigitalSignage_FR.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/nouvelles\\\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blackandmcdonald.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/blackandmcdonald.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#website\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/\",\"name\":\"Black & McDonald\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blackandmcdonald.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#organization\",\"name\":\"Black & McDonald\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/BlackMcDonald_Logo.png\",\"contentUrl\":\"https:\\\/\\\/blackandmcdonald.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/BlackMcDonald_Logo.png\",\"width\":1633,\"height\":844,\"caption\":\"Black & McDonald\"},\"image\":{\"@id\":\"https:\\\/\\\/blackandmcdonald.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BlackandMcDonald\",\"https:\\\/\\\/x.com\\\/bandmlimited\",\"https:\\\/\\\/www.instagram.com\\\/blackandmcdonald\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/black-&amp;-mcdonald-limited\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/blackmcdonaldchannel\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II - Black &amp; McDonald","description":"B&M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC\u00a027001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC\u00a02\u00ae Type\u00a0II.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/","og_locale":"fr_CA","og_type":"article","og_title":"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II","og_description":"B&amp;M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC&nbsp;27001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC&nbsp;2\u00ae","og_url":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/","og_site_name":"Black &amp; McDonald","article_publisher":"https:\/\/www.facebook.com\/BlackandMcDonald","article_modified_time":"2026-05-11T16:37:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/BM_ISO_Announcement_DigitalSignage_FR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bandmlimited","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/","url":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/","name":"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II - Black &amp; McDonald","isPartOf":{"@id":"https:\/\/blackandmcdonald.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/#primaryimage"},"image":{"@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/BM_ISO_Announcement_DigitalSignage_FR.jpg","datePublished":"2026-05-08T16:33:00+00:00","dateModified":"2026-05-11T16:37:00+00:00","description":"B&M a le plaisir d\u2019annoncer qu\u2019elle d\u00e9tient d\u00e9sormais la certification ISO\/IEC\u00a027001:2022 et qu\u2019elle a pass\u00e9 avec succ\u00e8s un audit SOC\u00a02\u00ae Type\u00a0II.","breadcrumb":{"@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/#primaryimage","url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/BM_ISO_Announcement_DigitalSignage_FR.jpg","contentUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/BM_ISO_Announcement_DigitalSignage_FR.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/blackandmcdonald.com\/fr\/nouvelles\/bm-obtient-la-certification-iso-27001-et-passe-laudit-soc-2-type-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackandmcdonald.com\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/blackandmcdonald.com\/news\/"},{"@type":"ListItem","position":3,"name":"B&amp;M obtient la certification\u00a0ISO\u00a027001 et passe l\u2019audit SOC\u00a02\u00ae Type\u00a0II"}]},{"@type":"WebSite","@id":"https:\/\/blackandmcdonald.com\/#website","url":"https:\/\/blackandmcdonald.com\/","name":"Black & McDonald","description":"","publisher":{"@id":"https:\/\/blackandmcdonald.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackandmcdonald.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/blackandmcdonald.com\/#organization","name":"Black & McDonald","url":"https:\/\/blackandmcdonald.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/blackandmcdonald.com\/#\/schema\/logo\/image\/","url":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/05\/BlackMcDonald_Logo.png","contentUrl":"https:\/\/blackandmcdonald.com\/wp-content\/uploads\/2020\/05\/BlackMcDonald_Logo.png","width":1633,"height":844,"caption":"Black & McDonald"},"image":{"@id":"https:\/\/blackandmcdonald.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BlackandMcDonald","https:\/\/x.com\/bandmlimited","https:\/\/www.instagram.com\/blackandmcdonald\/","https:\/\/www.linkedin.com\/company\/black-&amp;-mcdonald-limited","https:\/\/www.youtube.com\/user\/blackmcdonaldchannel"]}]}},"_links":{"self":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/news\/21623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/users\/25"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/media\/21625"}],"wp:attachment":[{"href":"https:\/\/blackandmcdonald.com\/fr\/wp-json\/wp\/v2\/media?parent=21623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}